{"id":1315,"count":1,"description":"","link":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/","name":"Patagonia","slug":"patagonia-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patagonia Archives - FIBGAR<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patagonia Archives - FIBGAR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/\" \/>\n<meta property=\"og:site_name\" content=\"FIBGAR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@fibgar_\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/tag\\\/patagonia-2\\\/\",\"url\":\"https:\\\/\\\/fibgar.es\\\/en\\\/tag\\\/patagonia-2\\\/\",\"name\":\"Patagonia Archives - FIBGAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/tag\\\/patagonia-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/tag\\\/patagonia-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fibgar.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patagonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fibgar.es\\\/en\\\/\",\"name\":\"FIBGAR\",\"description\":\"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#organization\"},\"alternateName\":\"FIBGAR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fibgar.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#organization\",\"name\":\"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n\",\"alternateName\":\"FIBGAR\",\"url\":\"https:\\\/\\\/fibgar.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fibgar.es\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-fibgar-icono.jpeg\",\"contentUrl\":\"https:\\\/\\\/fibgar.es\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-fibgar-icono.jpeg\",\"width\":512,\"height\":512,\"caption\":\"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/fibgar.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fibgar\",\"https:\\\/\\\/x.com\\\/fibgar_\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patagonia Archives - FIBGAR","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Patagonia Archives - FIBGAR","og_url":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/","og_site_name":"FIBGAR","twitter_card":"summary_large_image","twitter_site":"@fibgar_","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/","url":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/","name":"Patagonia Archives - FIBGAR","isPartOf":{"@id":"https:\/\/fibgar.es\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fibgar.es\/en\/tag\/patagonia-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fibgar.es\/en\/"},{"@type":"ListItem","position":2,"name":"Patagonia"}]},{"@type":"WebSite","@id":"https:\/\/fibgar.es\/en\/#website","url":"https:\/\/fibgar.es\/en\/","name":"FIBGAR","description":"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n","publisher":{"@id":"https:\/\/fibgar.es\/en\/#organization"},"alternateName":"FIBGAR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fibgar.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fibgar.es\/en\/#organization","name":"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n","alternateName":"FIBGAR","url":"https:\/\/fibgar.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fibgar.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fibgar.es\/wp-content\/uploads\/2020\/04\/cropped-fibgar-icono.jpeg","contentUrl":"https:\/\/fibgar.es\/wp-content\/uploads\/2020\/04\/cropped-fibgar-icono.jpeg","width":512,"height":512,"caption":"Fundaci\u00f3n Internacional Baltasar Garz\u00f3n"},"image":{"@id":"https:\/\/fibgar.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fibgar","https:\/\/x.com\/fibgar_"]}]}},"_links":{"self":[{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/tags\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/posts?tags=1315"},{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/tribe_events?tags=1315"},{"href":"https:\/\/fibgar.es\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}